{"id":4934,"date":"2021-06-12T06:25:44","date_gmt":"2021-06-12T04:25:44","guid":{"rendered":"https:\/\/wordpress.montagepartner-gmbh.de\/references\/"},"modified":"2026-06-29T17:00:46","modified_gmt":"2026-06-29T15:00:46","slug":"references","status":"publish","type":"page","link":"https:\/\/montagepartner-gmbh.de\/en\/references\/","title":{"rendered":"References"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4934\" class=\"elementor elementor-4934 elementor-11\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac9d44 e-flex e-con-boxed e-con e-parent\" data-id=\"0ac9d44\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-de3bad6 e-con-full e-flex e-con e-child\" data-id=\"de3bad6\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96b6ce3 e-flex e-con-boxed e-con e-parent\" data-id=\"96b6ce3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b56287a elementor-widget elementor-widget-spacer\" data-id=\"b56287a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57c7f79 e-con-full e-flex e-con e-child\" data-id=\"57c7f79\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4f6d743 e-con-full e-flex e-con e-child\" data-id=\"4f6d743\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7eeeb6 elementor-widget elementor-widget-icon-box\" data-id=\"c7eeeb6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOur long-standing partnership with MOPA is characterized by trust and reliability. As a longtime partner, Montagepartner GmbH understands our vision and values thoroughly and is perfectly aligned with them. It\u2019s simply a good feeling to know that everyone involved is giving their best to our joint projects.  \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9996419 e-con-full e-flex e-con e-child\" data-id=\"9996419\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f057663 elementor-position-left elementor-vertical-align-middle elementor-widget__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"f057663\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"359\" height=\"411\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/04\/Dieter-sw-e.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4846\" alt=\"Dieter Straub\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/04\/Dieter-sw-e.jpg 359w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/04\/Dieter-sw-e-262x300.jpg 262w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dieter Straub<\/h3><p class=\"elementor-image-box-description\">COO, Gielissen GmbH<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50a996d elementor-widget elementor-widget-spacer\" data-id=\"50a996d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5db29ae e-flex e-con-boxed e-con e-parent\" data-id=\"5db29ae\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dcc2cc2 e-con-full e-flex e-con e-child\" data-id=\"dcc2cc2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51be556 elementor-widget elementor-widget-image\" data-id=\"51be556\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1-300x210.jpg\" class=\"attachment-medium size-medium wp-image-6988\" alt=\"\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1-300x210.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1-1024x716.jpg 1024w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1-768x537.jpg 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1-1536x1073.jpg 1536w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2025\/09\/ads-tec_TheSmarterE2024_9341-scaled-1.jpg 1597w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Gunter Bieringer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47607a3 elementor-widget elementor-widget-heading\" data-id=\"47607a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ads-tec Holding GmbH<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9890cd8 elementor-widget elementor-widget-text-editor\" data-id=\"9890cd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/artistic.de\" target=\"_blank\" rel=\"noopener\">artistic werbewelten gmbh<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d20b76 e-con-full e-flex e-con e-child\" data-id=\"9d20b76\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f25c6f elementor-widget elementor-widget-image\" data-id=\"2f25c6f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-2_Frame_2_A-300x210.jpg\" class=\"attachment-medium size-medium wp-image-4517\" alt=\"MOPA Innenausbau - BMW Zentrale Frankreich\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-2_Frame_2_A-300x210.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-2_Frame_2_A-768x537.jpg 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-2_Frame_2_A.jpg 1022w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@R. Thieme <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94faf52 elementor-widget elementor-widget-heading\" data-id=\"94faf52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">BMW Headquarters in France<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0974963 elementor-widget elementor-widget-text-editor\" data-id=\"0974963\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Interior design commissioned by <a href=\"https:\/\/www.zeeh-design.com\" target=\"_blank\" rel=\"noopener\">Zeeh Design GmbH<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bde9078 e-con-full e-flex e-con e-child\" data-id=\"bde9078\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdf0747 elementor-widget elementor-widget-image\" data-id=\"fdf0747\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-100224_21_16_37-300x209.jpg\" class=\"attachment-medium size-medium wp-image-4525\" alt=\"MOPA Innenausbau - CosmosDirekt\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-100224_21_16_37-300x209.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU-100224_21_16_37.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@H. Weber <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792bf1a elementor-widget elementor-widget-heading\" data-id=\"792bf1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">CosmosDirekt  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe1d2b0 elementor-widget elementor-widget-text-editor\" data-id=\"fe1d2b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Complete renovation commissioned by Design Production GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66c7eb7 e-flex e-con-boxed e-con e-parent\" data-id=\"66c7eb7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-960983d e-con-full e-flex e-con e-child\" data-id=\"960983d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70f0ed3 elementor-widget elementor-widget-image\" data-id=\"70f0ed3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/EMAG_6610-Zuschnitt-300x209.jpeg\" class=\"attachment-medium size-medium wp-image-4533\" alt=\"Konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/EMAG_6610-Zuschnitt-300x209.jpeg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/EMAG_6610-Zuschnitt.jpeg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Gielissen GmbH - Gunter Bieringer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52f6043 elementor-widget elementor-widget-heading\" data-id=\"52f6043\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">EMAG GmbH &amp; Co. KG  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e05a2a elementor-widget elementor-widget-text-editor\" data-id=\"3e05a2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca4a1e7 e-con-full e-flex e-con e-child\" data-id=\"ca4a1e7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ffe527 elementor-widget elementor-widget-image\" data-id=\"0ffe527\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU_Impress_Interzum-2015-1-1-1-300x210.jpeg\" class=\"attachment-medium size-medium wp-image-4577\" alt=\"\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU_Impress_Interzum-2015-1-1-1-300x210.jpeg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU_Impress_Interzum-2015-1-1-1-768x537.jpeg 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/NEU_Impress_Interzum-2015-1-1-1.jpeg 1022w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6714761 elementor-widget elementor-widget-heading\" data-id=\"6714761\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">impress surfaces GmbH  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe8350e elementor-widget elementor-widget-text-editor\" data-id=\"fe8350e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f418abe e-con-full e-flex e-con e-child\" data-id=\"f418abe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88b6ade elementor-widget elementor-widget-image\" data-id=\"88b6ade\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/80922a-JVC-Gielissen-300x209.jpeg\" class=\"attachment-medium size-medium wp-image-4579\" alt=\"@Marco Cormann\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/80922a-JVC-Gielissen-300x209.jpeg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/80922a-JVC-Gielissen.jpeg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eab26fe elementor-widget elementor-widget-heading\" data-id=\"eab26fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">JVC Deutschland GmbH  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df94722 elementor-widget elementor-widget-text-editor\" data-id=\"df94722\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0566715 e-flex e-con-boxed e-con e-parent\" data-id=\"0566715\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-04086ce e-con-full e-flex e-con e-child\" data-id=\"04086ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0523768 elementor-widget elementor-widget-image\" data-id=\"0523768\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/362_Katjes-Kopie-2-300x210.jpeg\" class=\"attachment-medium size-medium wp-image-4603\" alt=\"Katjes - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/362_Katjes-Kopie-2-300x210.jpeg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/362_Katjes-Kopie-2.jpeg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Gielissen GmbH<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d24f1e elementor-widget elementor-widget-heading\" data-id=\"8d24f1e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Katjes  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-587b06f elementor-widget elementor-widget-text-editor\" data-id=\"587b06f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-421f08c e-con-full e-flex e-con e-child\" data-id=\"421f08c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa2148 elementor-widget elementor-widget-image\" data-id=\"0aa2148\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Komet480x336-300x210.jpg\" class=\"attachment-medium size-medium wp-image-4605\" alt=\"MOPA - Konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Komet480x336-300x210.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Komet480x336.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Feuss Photography<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-681f92d elementor-widget elementor-widget-heading\" data-id=\"681f92d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Komet Dental  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f60cf59 elementor-widget elementor-widget-text-editor\" data-id=\"f60cf59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction on Behalf of Bluepool GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc9765b e-con-full e-flex e-con e-child\" data-id=\"dc9765b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b700aa5 elementor-widget elementor-widget-image\" data-id=\"b700aa5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Kuka-480x355-1-300x209.jpg\" class=\"attachment-medium size-medium wp-image-4617\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Kuka-480x355-1-300x209.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/02\/Kuka-480x355-1.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Fotodesign Schiermann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acd2abd elementor-widget elementor-widget-heading\" data-id=\"acd2abd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Kuka Aktiengesellschaft  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08d53eb elementor-widget elementor-widget-text-editor\" data-id=\"08d53eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction on Behalf of Bluepool GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bed8547 e-flex e-con-boxed e-con e-parent\" data-id=\"bed8547\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6901011 e-con-full e-flex e-con e-child\" data-id=\"6901011\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98b5ce7 elementor-widget elementor-widget-image\" data-id=\"98b5ce7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480X355-IMG_6944-Zuschnitt-300x209.jpg\" class=\"attachment-medium size-medium wp-image-4627\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480X355-IMG_6944-Zuschnitt-300x209.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480X355-IMG_6944-Zuschnitt.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d5eb8a elementor-widget elementor-widget-heading\" data-id=\"9d5eb8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MEBA METALL GMBH  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a1ef4 elementor-widget elementor-widget-text-editor\" data-id=\"80a1ef4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a66c1b e-con-full e-flex e-con e-child\" data-id=\"4a66c1b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f24eda elementor-widget elementor-widget-image\" data-id=\"8f24eda\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480355-Mebra-300x209.webp\" class=\"attachment-medium size-medium wp-image-4633\" alt=\"MOPA - Referenzbild konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480355-Mebra-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/480355-Mebra.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH - Stefan R\u00f6hler<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7fd9dc elementor-widget elementor-widget-heading\" data-id=\"a7fd9dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MEKRA Lang GmbH &amp; Co. KG<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc5ef6 elementor-widget elementor-widget-text-editor\" data-id=\"1cc5ef6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e262d5 e-con-full e-flex e-con e-child\" data-id=\"1e262d5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64868a7 elementor-widget elementor-widget-image\" data-id=\"64868a7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MBenz480x355-300x209.webp\" class=\"attachment-medium size-medium wp-image-4641\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MBenz480x355-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MBenz480x355.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9R. Thieme <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-102b5d4 elementor-widget elementor-widget-heading\" data-id=\"102b5d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mercedes-Benz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e8ceab elementor-widget elementor-widget-text-editor\" data-id=\"7e8ceab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction on Behalf of Bluepool GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a77c0d8 e-flex e-con-boxed e-con e-parent\" data-id=\"a77c0d8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a32331f e-con-full e-flex e-con e-child\" data-id=\"a32331f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e115c12 elementor-widget elementor-widget-image\" data-id=\"e115c12\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/20230920_Gielissen-Mitutoyo_058-Zuschnitt-300x209.webp\" class=\"attachment-medium size-medium wp-image-4663\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/20230920_Gielissen-Mitutoyo_058-Zuschnitt-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/20230920_Gielissen-Mitutoyo_058-Zuschnitt.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH - Stefan R\u00f6hler<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c60cee5 elementor-widget elementor-widget-heading\" data-id=\"c60cee5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mitutoyo Deutschland GmbH  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ccc0e elementor-widget elementor-widget-text-editor\" data-id=\"45ccc0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc57275 e-con-full e-flex e-con e-child\" data-id=\"cc57275\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40da0ce elementor-widget elementor-widget-image\" data-id=\"40da0ce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Molex-3-Electronica-16-ok-300x209.webp\" class=\"attachment-medium size-medium wp-image-4679\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Molex-3-Electronica-16-ok-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Molex-3-Electronica-16-ok.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6781228 elementor-widget elementor-widget-heading\" data-id=\"6781228\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MOLEX Deutschland GmbH  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dcff86 elementor-widget elementor-widget-text-editor\" data-id=\"4dcff86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa36b8f e-con-full e-flex e-con e-child\" data-id=\"aa36b8f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f414a3c elementor-widget elementor-widget-image\" data-id=\"f414a3c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MTU-1209041SMM-HH-3-300x209.webp\" class=\"attachment-medium size-medium wp-image-4697\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MTU-1209041SMM-HH-3-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MTU-1209041SMM-HH-3-768x536.webp 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/MTU-1209041SMM-HH-3.webp 976w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9X-P3 Photography UG<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdc5d20 elementor-widget elementor-widget-heading\" data-id=\"fdc5d20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MTU Friedrichshafen GmbH<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-463f602 elementor-widget elementor-widget-text-editor\" data-id=\"463f602\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction on Behalf of Bluepool GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c665c0 e-flex e-con-boxed e-con e-parent\" data-id=\"3c665c0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-82555dd e-con-full e-flex e-con e-child\" data-id=\"82555dd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37303e3 elementor-widget elementor-widget-image\" data-id=\"37303e3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Horn-480x335-1-300x209.webp\" class=\"attachment-medium size-medium wp-image-4733\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Horn-480x335-1-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Horn-480x335-1.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH - Stefan R\u00f6hler<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88fe325 elementor-widget elementor-widget-heading\" data-id=\"88fe325\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Paul Horn, LLC  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76bc518 elementor-widget elementor-widget-text-editor\" data-id=\"76bc518\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f834e3 e-con-full e-flex e-con e-child\" data-id=\"3f834e3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c3ef29 elementor-widget elementor-widget-text-editor\" data-id=\"5c3ef29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a45471d elementor-widget elementor-widget-image\" data-id=\"a45471d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Rehau_klein-300x209.webp\" class=\"attachment-medium size-medium wp-image-4711\" alt=\"MOPA - Referenzbild\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Rehau_klein-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Rehau_klein.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de4c700 elementor-widget elementor-widget-heading\" data-id=\"de4c700\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Rehau<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eedaa37 e-con-full e-flex e-con e-child\" data-id=\"eedaa37\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e6fc05 elementor-widget elementor-widget-image\" data-id=\"0e6fc05\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Renz_klein-300x209.webp\" class=\"attachment-medium size-medium wp-image-4723\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Renz_klein-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Renz_klein.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9 Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad57699 elementor-widget elementor-widget-heading\" data-id=\"ad57699\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Renz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7f913 elementor-widget elementor-widget-text-editor\" data-id=\"fb7f913\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d940c93 e-flex e-con-boxed e-con e-parent\" data-id=\"d940c93\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44a0e62 e-con-full e-flex e-con e-child\" data-id=\"44a0e62\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d97fe02 elementor-widget elementor-widget-image\" data-id=\"d97fe02\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-300x200.jpg\" class=\"attachment-medium size-medium wp-image-6367\" alt=\"\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-300x200.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-1024x683.jpg 1024w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-768x512.jpg 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-1536x1024.jpg 1536w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/07\/SolarLog_TheSmarterE2024_9476-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@Gunter Bieringer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-327e2cd elementor-widget elementor-widget-heading\" data-id=\"327e2cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Solar-Log GmbH<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b654bba elementor-widget elementor-widget-text-editor\" data-id=\"b654bba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/artistic.de\" target=\"_blank\" rel=\"noopener\">artistic werbewelten gmbh<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbb241e e-con-full e-flex e-con e-child\" data-id=\"bbb241e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28b6bf2 elementor-widget elementor-widget-text-editor\" data-id=\"28b6bf2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e3bd0 elementor-widget elementor-widget-image\" data-id=\"68e3bd0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Volvo480x335-300x210.jpg\" class=\"attachment-medium size-medium wp-image-4797\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Volvo480x335-300x210.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Volvo480x335.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH - Gunter Bieringer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2dfa3d elementor-widget elementor-widget-heading\" data-id=\"e2dfa3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Volvo Trucks  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-660ecb0 e-con-full e-flex e-con e-child\" data-id=\"660ecb0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f021e6a elementor-widget elementor-widget-image\" data-id=\"f021e6a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Weiser-480x335-1-300x209.webp\" class=\"attachment-medium size-medium wp-image-4745\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Weiser-480x335-1-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Weiser-480x335-1.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9KD-Busch<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764b5c4 elementor-widget elementor-widget-heading\" data-id=\"764b5c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">J.G. WEISSER SOEHNE GmbH &amp; Co.  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da822f9 elementor-widget elementor-widget-text-editor\" data-id=\"da822f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cda949 e-flex e-con-boxed e-con e-parent\" data-id=\"3cda949\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ebbcbc e-con-full e-flex e-con e-child\" data-id=\"7ebbcbc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7da48 elementor-widget elementor-widget-image\" data-id=\"cc7da48\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Winterhalter480x335-300x209.webp\" class=\"attachment-medium size-medium wp-image-4753\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Winterhalter480x335-300x209.webp 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Winterhalter480x335.webp 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b689c2a elementor-widget elementor-widget-heading\" data-id=\"b689c2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Winterhalter GmbH Germany  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0040c06 elementor-widget elementor-widget-text-editor\" data-id=\"0040c06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional Booth Construction Commissioned by <a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fa0e93 e-con-full e-flex e-con e-child\" data-id=\"9fa0e93\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acafb36 elementor-widget elementor-widget-text-editor\" data-id=\"acafb36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional booth construction commissioned by <br \/><a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-322b657 elementor-widget elementor-widget-image\" data-id=\"322b657\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/WMF-Hotel-2-Internorga-2015-ok-300x210.jpeg\" class=\"attachment-medium size-medium wp-image-4777\" alt=\"\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/WMF-Hotel-2-Internorga-2015-ok-300x210.jpeg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/WMF-Hotel-2-Internorga-2015-ok-768x537.jpeg 768w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/WMF-Hotel-2-Internorga-2015-ok.jpeg 1022w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cd073f elementor-widget elementor-widget-heading\" data-id=\"0cd073f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">  WMF Hotel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80e41c7 e-con-full e-flex e-con e-child\" data-id=\"80e41c7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b145a9 elementor-widget elementor-widget-image\" data-id=\"7b145a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yamaha480x335-300x209.jpg\" class=\"attachment-medium size-medium wp-image-4781\" alt=\"MOPA - konventioneller Standbau\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yamaha480x335-300x209.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yamaha480x335.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Marco Cormann<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4a7a2 elementor-widget elementor-widget-heading\" data-id=\"1d4a7a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Yamaha<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75af117 elementor-widget elementor-widget-text-editor\" data-id=\"75af117\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional booth construction commissioned by <br \/><a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-993261e e-flex e-con-boxed e-con e-parent\" data-id=\"993261e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ca48d3 e-con-full e-flex e-con e-child\" data-id=\"7ca48d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78cc409 elementor-widget elementor-widget-image\" data-id=\"78cc409\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yasda480x335-300x209.jpg\" class=\"attachment-medium size-medium wp-image-4789\" alt=\"MO\" srcset=\"https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yasda480x335-300x209.jpg 300w, https:\/\/montagepartner-gmbh.de\/wp-content\/uploads\/2024\/03\/Yasda480x335.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9Gielissen GmbH<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d9d04 elementor-widget elementor-widget-heading\" data-id=\"16d9d04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">YASDA PRECISION TOOLS K.K.  <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfbf994 elementor-widget elementor-widget-text-editor\" data-id=\"bfbf994\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Conventional booth construction commissioned by <br \/><a href=\"https:\/\/www.gielissen.com\/de\/\" target=\"_blank\" rel=\"noopener\">Gielissen GmbH, G\u00f6ppingen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be45fed e-flex e-con-boxed e-con e-parent\" data-id=\"be45fed\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f65e24c elementor-widget elementor-widget-spacer\" data-id=\"f65e24c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfe845a elementor-widget elementor-widget-spacer\" data-id=\"dfe845a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ba97a5 elementor-widget elementor-widget-spacer\" data-id=\"4ba97a5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9618cb elementor-widget elementor-widget-spacer\" data-id=\"f9618cb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d211bfb elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"d211bfb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d889aa e-flex e-con-boxed e-con e-parent\" data-id=\"4d889aa\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-378ac05 elementor-widget elementor-widget-spacer\" data-id=\"378ac05\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7d170a e-flex e-con-boxed e-con e-parent\" data-id=\"f7d170a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4d9eed e-flex e-con-boxed e-con e-child\" data-id=\"c4d9eed\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4dfbd66 e-con-full e-flex e-con e-child\" data-id=\"4dfbd66\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-152a967 elementor-widget elementor-widget-heading\" data-id=\"152a967\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Contact us<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ae5ce8 elementor-widget elementor-widget-icon-box\" data-id=\"0ae5ce8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDie Montagepartner GmbH\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36aeda4 elementor-widget elementor-widget-text-editor\" data-id=\"36aeda4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400\">Bieselberger Weg 11<br data-start=\"100\" data-end=\"103\" \/>75399 Unterreichenbach<br \/>mail@montagepartner-gmbh.de<br \/>Tel. +49 173 36 60 758<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52ef415 e-con-full e-flex e-con e-child\" data-id=\"52ef415\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8881ef elementor-widget elementor-widget-heading\" data-id=\"f8881ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">We look forward to working with you<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be72d3 elementor-widget elementor-widget-heading\" data-id=\"0be72d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Get in touch with us!<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9543489 elementor-widget elementor-widget-wpforms\" data-id=\"9543489\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container \" id=\"wpforms-1271\"><form id=\"wpforms-form-1271\" class=\"wpforms-validate wpforms-form\" data-formid=\"1271\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4934\" data-token=\"6841861da875aca5f0714e3d25a430a4\" data-token-time=\"1784153277\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1271-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1271-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1271-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Name\" required><\/div><div id=\"wpforms-1271-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1271-field_8\">Single Line Text<\/label><input type=\"text\" id=\"wpforms-1271-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" placeholder=\"Phone number\" ><\/div><div id=\"wpforms-1271-field_7-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1271-field_7\">Your e-mail address <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1271-field_7\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][7]\" placeholder=\"e-mail\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1271-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1271-field_2\">Your message to us <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-1271-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Message\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container -->\r\n\t\t\t<script>\r\n\t\t\tif ( typeof huOptions !== 'undefined' ) {\r\n\t\t\t\tvar huFormData = [];\r\n\t\t\t\tvar huFormNode = document.querySelector( '[id=\"wpforms-1271\"] form' );\r\n\r\n\t\t\t\tvar firstName = huFormNode.querySelector( 'input.wpforms-field-name-first' );\r\n\t\t\t\tvar lastName = huFormNode.querySelector( 'input.wpforms-field-name-last' );\r\n\r\n\t\t\t\tif ( firstName )\r\n\t\t\t\t\thuFormData['fields']['subject']['first_name'] = firstName.getAttribute( 'name' );\r\n\r\n\t\t\t\tif ( lastName )\r\n\t\t\t\t\thuFormData['fields']['subject']['last_name'] = lastName.getAttribute( 'name' );\r\n\r\n\t\t\t\thuFormData['node'] = huFormNode;\r\n\t\t\t\thuOptions['forms'].push( huFormData );\r\n\t\t\t}\r\n\t\t\t<\/script><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1271\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/pages\/4934\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1271\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our long-standing partnership with MOPA is characterized by trust and reliability. As a longtime partner, Montagepartner GmbH understands our vision and values thoroughly and is perfectly aligned with them. It\u2019s simply a good feeling to know that everyone involved is giving their best to our joint projects. Dieter Straub COO, Gielissen GmbH @Gunter Bieringer ads-tec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4934","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/pages\/4934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/comments?post=4934"}],"version-history":[{"count":12,"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/pages\/4934\/revisions"}],"predecessor-version":[{"id":7267,"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/pages\/4934\/revisions\/7267"}],"wp:attachment":[{"href":"https:\/\/montagepartner-gmbh.de\/en\/wp-json\/wp\/v2\/media?parent=4934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}